{"id":445,"count":1,"description":"","link":"https:\/\/alicia.cat\/es\/publicacions-tag\/lechuga-es\/","name":"lechuga","slug":"lechuga-es","taxonomy":"etiquetes_de_publicacions","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arxius de lechuga - Fundaci\u00f3 Al\u00edcia<\/title>\n<meta name=\"description\" content=\"Publicacions amb etiquetes de lechuga - .\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alicia.cat\/es\/publicacions-tag\/lechuga-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arxius de lechuga - Fundaci\u00f3 Al\u00edcia\" \/>\n<meta property=\"og:description\" content=\"Publicacions amb etiquetes de lechuga - .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alicia.cat\/es\/publicacions-tag\/lechuga-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Al\u00edcia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alicia.cat\/wp-content\/uploads\/2023\/04\/c1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FundacioAlicia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/alicia.cat\\\/es\\\/publicacions-tag\\\/lechuga-es\\\/\",\"url\":\"https:\\\/\\\/alicia.cat\\\/es\\\/publicacions-tag\\\/lechuga-es\\\/\",\"name\":\"Arxius de lechuga - Fundaci\u00f3 Al\u00edcia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alicia.cat\\\/es\\\/#website\"},\"description\":\"Publicacions amb etiquetes de lechuga - .\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alicia.cat\\\/es\\\/publicacions-tag\\\/lechuga-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alicia.cat\\\/es\\\/publicacions-tag\\\/lechuga-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/alicia.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"lechuga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alicia.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/alicia.cat\\\/es\\\/\",\"name\":\"Fundaci\u00f3 Al\u00edcia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/alicia.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alicia.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alicia.cat\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Al\u00edcia\",\"alternateName\":\"Al\u00edcia\",\"url\":\"https:\\\/\\\/alicia.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alicia.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alicia.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_alicia.svg\",\"contentUrl\":\"https:\\\/\\\/alicia.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_alicia.svg\",\"caption\":\"Fundaci\u00f3 Al\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/alicia.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FUNDACIOALICIA\",\"https:\\\/\\\/x.com\\\/FundacioAlicia\",\"https:\\\/\\\/www.instagram.com\\\/fundacioalicia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacionalicia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/FundacioAlicia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arxius de lechuga - Fundaci\u00f3 Al\u00edcia","description":"Publicacions amb etiquetes de lechuga - .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alicia.cat\/es\/publicacions-tag\/lechuga-es\/","og_locale":"es_ES","og_type":"article","og_title":"Arxius de lechuga - Fundaci\u00f3 Al\u00edcia","og_description":"Publicacions amb etiquetes de lechuga - .","og_url":"https:\/\/alicia.cat\/es\/publicacions-tag\/lechuga-es\/","og_site_name":"Fundaci\u00f3 Al\u00edcia","og_image":[{"width":1120,"height":515,"url":"https:\/\/alicia.cat\/wp-content\/uploads\/2023\/04\/c1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@FundacioAlicia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/alicia.cat\/es\/publicacions-tag\/lechuga-es\/","url":"https:\/\/alicia.cat\/es\/publicacions-tag\/lechuga-es\/","name":"Arxius de lechuga - Fundaci\u00f3 Al\u00edcia","isPartOf":{"@id":"https:\/\/alicia.cat\/es\/#website"},"description":"Publicacions amb etiquetes de lechuga - .","breadcrumb":{"@id":"https:\/\/alicia.cat\/es\/publicacions-tag\/lechuga-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/alicia.cat\/es\/publicacions-tag\/lechuga-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/alicia.cat\/es\/"},{"@type":"ListItem","position":2,"name":"lechuga"}]},{"@type":"WebSite","@id":"https:\/\/alicia.cat\/es\/#website","url":"https:\/\/alicia.cat\/es\/","name":"Fundaci\u00f3 Al\u00edcia","description":"","publisher":{"@id":"https:\/\/alicia.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alicia.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/alicia.cat\/es\/#organization","name":"Fundaci\u00f3 Al\u00edcia","alternateName":"Al\u00edcia","url":"https:\/\/alicia.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alicia.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/alicia.cat\/wp-content\/uploads\/2023\/02\/logo_alicia.svg","contentUrl":"https:\/\/alicia.cat\/wp-content\/uploads\/2023\/02\/logo_alicia.svg","caption":"Fundaci\u00f3 Al\u00edcia"},"image":{"@id":"https:\/\/alicia.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FUNDACIOALICIA","https:\/\/x.com\/FundacioAlicia","https:\/\/www.instagram.com\/fundacioalicia\/","https:\/\/www.linkedin.com\/company\/fundacionalicia\/","https:\/\/www.youtube.com\/FundacioAlicia"]}]}},"_links":{"self":[{"href":"https:\/\/alicia.cat\/es\/wp-json\/wp\/v2\/etiquetes_de_publicacions\/445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alicia.cat\/es\/wp-json\/wp\/v2\/etiquetes_de_publicacions"}],"about":[{"href":"https:\/\/alicia.cat\/es\/wp-json\/wp\/v2\/taxonomies\/etiquetes_de_publicacions"}],"wp:post_type":[{"href":"https:\/\/alicia.cat\/es\/wp-json\/wp\/v2\/publicacions?etiquetes_de_publicacions=445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}